                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                        {"id":1016,"date":"2021-04-18T13:51:42","date_gmt":"2021-04-18T20:51:42","guid":{"rendered":"http:\/\/bentonco.spectrespast.com\/?page_id=1016"},"modified":"2022-05-07T06:30:44","modified_gmt":"2022-05-07T13:30:44","slug":"week-one-bridging-the-divide","status":"publish","type":"page","link":"https:\/\/bentonco.spectrespast.com\/es\/game-landing-page\/week-one-bridging-the-divide\/","title":{"rendered":"Episodio uno - Uniendo la brecha"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1016\" class=\"elementor elementor-1016\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ec4bbc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ec4bbc\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-63bad98\" data-id=\"63bad98\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f4a7bd elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"0f4a7bd\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/bentonco.spectrespast.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-nav-menu.min.css\">\t\t\t<nav class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-0f4a7bd\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1026\"><a href=\"https:\/\/bentonco.spectrespast.com\/es\/game-landing-page\/\" class=\"elementor-item\">Informaci\u00f3n general del juego<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3454\"><a href=\"https:\/\/bentonco.spectrespast.com\/es\/game-landing-page\/week-one-bridging-the-divide\/\" class=\"elementor-item\">Episodio uno - Uniendo la brecha<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3453\"><a href=\"https:\/\/bentonco.spectrespast.com\/es\/game-landing-page\/episode-two-schooling-women-2\/\" class=\"elementor-item\">Episodio dos - Escolarizaci\u00f3n de mujeres<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3452\"><a href=\"https:\/\/bentonco.spectrespast.com\/es\/game-landing-page\/episode-four-granger-things\/\" class=\"elementor-item\">Episodio tres - Cosas de Granger<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Alternar men\u00fa\" aria-expanded=\"false\">\n\t\t\t<svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open e-font-icon-svg e-eicon-menu-bar\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M104 333H896C929 333 958 304 958 271S929 208 896 208H104C71 208 42 237 42 271S71 333 104 333ZM104 583H896C929 583 958 554 958 521S929 458 896 458H104C71 458 42 487 42 521S71 583 104 583ZM104 833H896C929 833 958 804 958 771S929 708 896 708H104C71 708 42 737 42 771S71 833 104 833Z\"><\/path><\/svg><svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close e-font-icon-svg e-eicon-close\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M742 167L500 408 258 167C246 154 233 150 217 150 196 150 179 158 167 167 154 179 150 196 150 212 150 229 154 242 171 254L408 500 167 742C138 771 138 800 167 829 196 858 225 858 254 829L496 587 738 829C750 842 767 846 783 846 800 846 817 842 829 829 842 817 846 804 846 783 846 767 842 750 829 737L588 500 833 258C863 229 863 200 833 171 804 137 775 137 742 167Z\"><\/path><\/svg>\t\t\t<span class=\"elementor-screen-only\">Men\u00fa<\/span>\n\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-0f4a7bd\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1026\"><a href=\"https:\/\/bentonco.spectrespast.com\/es\/game-landing-page\/\" class=\"elementor-item\" tabindex=\"-1\">Informaci\u00f3n general del juego<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3454\"><a href=\"https:\/\/bentonco.spectrespast.com\/es\/game-landing-page\/week-one-bridging-the-divide\/\" class=\"elementor-item\" tabindex=\"-1\">Episodio uno - Uniendo la brecha<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3453\"><a href=\"https:\/\/bentonco.spectrespast.com\/es\/game-landing-page\/episode-two-schooling-women-2\/\" class=\"elementor-item\" tabindex=\"-1\">Episodio dos - Escolarizaci\u00f3n de mujeres<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3452\"><a href=\"https:\/\/bentonco.spectrespast.com\/es\/game-landing-page\/episode-four-granger-things\/\" class=\"elementor-item\" tabindex=\"-1\">Episodio tres - Cosas de Granger<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65f0864 elementor-drop-cap-yes elementor-drop-cap-view-default elementor-widget elementor-widget-text-editor\" data-id=\"65f0864\" data-element_type=\"widget\" data-settings=\"{&quot;drop_cap&quot;:&quot;yes&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.12.1 - 02-04-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Y<em>nuestra aventura comienza en una estructura que fue pionera en su \u00e9poca: 1913: el puente van Buren; y en su prop\u00f3sito: conectar personas y medios de transporte en el condado de Benton y Corvallis sobre el poderoso r\u00edo Willamette.<\/em><\/p><p><em>\u00a1Imag\u00ednese atravesar un delgado velo en el tiempo y el espacio, que lo llevar\u00e1 a una misi\u00f3n de rescate! Aunque rescatar a una persona es en s\u00ed mismo una cosa importante que hacer, la persona a la que est\u00e1 ayudando tiene una tarea importante que \u00c9L tambi\u00e9n tiene la intenci\u00f3n de realizar.<\/em><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5281d13 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5281d13\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-95b5c48\" data-id=\"95b5c48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27e7dac elementor-widget elementor-widget-text-editor\" data-id=\"27e7dac\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3>TU MISI\u00d3N<\/h3><p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1956 aligncenter\" src=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/exisisting-bridge-Converted.png\" alt=\"\" width=\"600\" height=\"248\" srcset=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/exisisting-bridge-Converted.png 954w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/exisisting-bridge-Converted-300x124.png 300w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/exisisting-bridge-Converted-768x317.png 768w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/exisisting-bridge-Converted-16x7.png 16w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p><blockquote><p>Vuelva a representar uno de los fascinantes incidentes del pasado variado e hist\u00f3rico del puente Van Buren: poco despu\u00e9s de que el puente se puso en servicio por primera vez, se revel\u00f3 dram\u00e1ticamente un descuido en el dise\u00f1o.<\/p><\/blockquote>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88c3293 elementor-widget elementor-widget-text-editor\" data-id=\"88c3293\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3>SUS OBJETIVOS<\/h3><p>Resuelva los desaf\u00edos comenzando haciendo clic en el <strong><a href=\"https:\/\/bentonco.spectrespast.com\/es\/week-1-web\/\" target=\"_blank\" rel=\"noopener\">AVENTURA VIRTUAL<\/a><\/strong> para desentra\u00f1ar la historia y descubrir lo que realmente estaba sucediendo en ese fat\u00eddico d\u00eda.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acb5573 elementor-widget elementor-widget-text-editor\" data-id=\"acb5573\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3>HERRAMIENTAS Y PIEZAS DE JUEGO<\/h3><p>Haga clic en el <strong><a href=\"https:\/\/bentonco.spectrespast.com\/es\/week-1-web\/\" target=\"_blank\" rel=\"noopener\">AVENTURA VIRTUAL<\/a><\/strong> en la esquina superior derecha para comenzar.<\/p><p>O, si tiene la intenci\u00f3n de hacer esta aventura EN EL TERRENO, descargue la versi\u00f3n PDF para obtener la versi\u00f3n en papel antigua. O instale Actionbound <a href=\"\/es\/actionbound\/\">(instrucciones aqu\u00ed)<\/a> en tu m\u00f3vil y escanea el c\u00f3digo para empezar a usarlo.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<!-- hidden widget -->\t\t<div class=\"elementor-element elementor-element-3d55d71 elementor-tabs-view-horizontal elementor-widget elementor-widget-global elementor-global-2706 elementor-widget-tabs\" data-id=\"3d55d71\" data-element_type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.12.1 - 02-04-2023 *\/\n.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tabs-wrapper{width:25%;flex-shrink:0}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active{border-right-style:none}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active:after,.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active:before{height:999em;width:0;right:0;border-right-style:solid}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active:before{top:0;transform:translateY(-100%)}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active:after{top:100%}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title{display:table-cell}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active{border-bottom-style:none}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active:after,.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active:before{bottom:0;height:0;width:999em;border-bottom-style:solid}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active:before{right:100%}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active:after{left:100%}.elementor-widget-tabs .elementor-tab-content,.elementor-widget-tabs .elementor-tab-title,.elementor-widget-tabs .elementor-tab-title:after,.elementor-widget-tabs .elementor-tab-title:before,.elementor-widget-tabs .elementor-tabs-content-wrapper{border:1px #d5d8dc}.elementor-widget-tabs .elementor-tabs{text-align:left}.elementor-widget-tabs .elementor-tabs-wrapper{overflow:hidden}.elementor-widget-tabs .elementor-tab-title{cursor:pointer;outline:var(--focus-outline,none)}.elementor-widget-tabs .elementor-tab-desktop-title{position:relative;padding:20px 25px;font-weight:700;line-height:1;border:solid transparent}.elementor-widget-tabs .elementor-tab-desktop-title.elementor-active{border-color:#d5d8dc}.elementor-widget-tabs .elementor-tab-desktop-title.elementor-active:after,.elementor-widget-tabs .elementor-tab-desktop-title.elementor-active:before{display:block;content:\"\";position:absolute}.elementor-widget-tabs .elementor-tab-desktop-title:focus-visible{border:1px solid #000}.elementor-widget-tabs .elementor-tab-mobile-title{padding:10px;cursor:pointer}.elementor-widget-tabs .elementor-tab-content{padding:20px;display:none}@media (max-width:767px){.elementor-tabs .elementor-tab-content,.elementor-tabs .elementor-tab-title{border-style:solid solid none}.elementor-tabs .elementor-tabs-wrapper{display:none}.elementor-tabs .elementor-tabs-content-wrapper{border-bottom-style:solid}.elementor-tabs .elementor-tab-content{padding:10px}}@media (min-width:768px){.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tabs{display:flex}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tabs-wrapper{flex-direction:column}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tabs-content-wrapper{flex-grow:1;border-style:solid solid solid none}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-content{border-style:none solid solid}.elementor-widget-tabs.elementor-tabs-alignment-center .elementor-tabs-wrapper,.elementor-widget-tabs.elementor-tabs-alignment-end .elementor-tabs-wrapper,.elementor-widget-tabs.elementor-tabs-alignment-stretch .elementor-tabs-wrapper{display:flex}.elementor-widget-tabs.elementor-tabs-alignment-center .elementor-tabs-wrapper{justify-content:center}.elementor-widget-tabs.elementor-tabs-alignment-end .elementor-tabs-wrapper{justify-content:flex-end}.elementor-widget-tabs.elementor-tabs-alignment-stretch.elementor-tabs-view-horizontal .elementor-tab-title{width:100%}.elementor-widget-tabs.elementor-tabs-alignment-stretch.elementor-tabs-view-vertical .elementor-tab-title{height:100%}.elementor-tabs .elementor-tab-mobile-title{display:none}}<\/style>\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6431\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-6431\" aria-expanded=\"false\">SUGERENCIAS<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6432\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6432\" aria-expanded=\"false\">Web #1<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6433\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6433\" aria-expanded=\"false\">Web #2<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6434\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6434\" aria-expanded=\"false\">Web #3<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6435\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6435\" aria-expanded=\"false\">Ubicaci\u00f3n en el suelo<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6436\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6436\" aria-expanded=\"false\">Todos los tipos de juegos Sugerencia <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-6431\" aria-expanded=\"false\">SUGERENCIAS<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6431\" tabindex=\"0\" hidden=\"false\"><h4><strong>\u00a1Alerta de spoiler!<\/strong> Las SUGERENCIAS en las pesta\u00f1as de arriba contienen informaci\u00f3n que le permitir\u00e1 completar los desaf\u00edos, si est\u00e1 atascado o bloqueado.<\/h4><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6432\" aria-expanded=\"false\">Web #1<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6432\" tabindex=\"0\" hidden=\"hidden\"><p>30 segundos despu\u00e9s de que se cargue el rompecabezas deslizante, aparece un bot\u00f3n que le permite omitir el rompecabezas.\u00a0<\/p><p><a href=\"\/es\/week-1-web\/\">De vuelta al rompecabezas.<\/a><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6433\" aria-expanded=\"false\">Web #2<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6433\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6433\" tabindex=\"0\" hidden=\"hidden\"><p>Para responder las preguntas del cuestionario, haga clic en la imagen de la galer\u00eda correspondiente a la miniatura de la pregunta. Esto le dar\u00e1 una vista m\u00e1s amplia de la parte relevante del Marcador hist\u00f3rico a partir de la cual derivar sus respuestas.<\/p><p><a href=\"\/es\/bridge-challenge\/\">De vuelta al desaf\u00edo.<\/a><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6434\" aria-expanded=\"false\">Web #3<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6434\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6434\" tabindex=\"0\" hidden=\"hidden\"><p>El cuarto n\u00famero en la posici\u00f3n 7 es el mismo que el primero.<\/p><p><a href=\"\/es\/bridge-challenge\/\">De vuelta al desaf\u00edo<\/a>.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6435\" aria-expanded=\"false\">Ubicaci\u00f3n en el suelo<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6435\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6435\" tabindex=\"0\" hidden=\"hidden\"><p>Hay DOS marcadores hist\u00f3ricos en la primera ubicaci\u00f3n. Utilice el m\u00e1s al norte para responder las preguntas del cuestionario.<\/p><p><strong>Recuerde, On the Ground se refiere tanto a la aplicaci\u00f3n de tel\u00e9fono Actionbound como a las versiones en PDF.<\/strong><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6436\" aria-expanded=\"false\">Todos los tipos de juegos Sugerencia <\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6436\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6436\" tabindex=\"0\" hidden=\"hidden\"><p>Las respuestas a TODAS las preguntas del cuestionario son n\u00fameros de 1, 2 o 3 d\u00edgitos. Las respuestas en el orden en que se presentan las preguntas le dan un n\u00famero de tel\u00e9fono de 10 d\u00edgitos.<\/p><p><a href=\"\/es\/bridge-challenge\/\" target=\"_blank\" rel=\"noopener\">De vuelta al desaf\u00edo<\/a>.<\/p><p><a href=\"\/es\/sprint-to-the-next-challenge\/\" target=\"_blank\" rel=\"noopener\">O SALTE para revelar.<\/a><\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1320a3e elementor-widget elementor-widget-heading\" data-id=\"1320a3e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sugerencias para el desaf\u00edo 2: galletas saladas<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ba6bb6 elementor-widget elementor-widget-menu-anchor\" data-id=\"2ba6bb6\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.12.1 - 02-04-2023 *\/\nbody.elementor-page .elementor-widget-menu-anchor{margin-bottom:0}<\/style>\t\t<div id=\"E1C2hints\" class=\"elementor-menu-anchor\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3fe834 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"e3fe834\" data-element_type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2391\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2391\" aria-expanded=\"false\">SUGERENCIAS<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2391\" aria-expanded=\"false\">SUGERENCIAS<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2391\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2391\" tabindex=\"0\" hidden=\"false\"><h4><strong>\u00a1Alerta de spoiler!<\/strong> Las SUGERENCIAS en las pesta\u00f1as de arriba contienen informaci\u00f3n que le permitir\u00e1 completar los desaf\u00edos, si est\u00e1 atascado o bloqueado.<\/h4><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d3be1a2 dc-has-condition dc-condition-greater\" data-id=\"d3be1a2\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0bca48e elementor-widget elementor-widget-heading\" data-id=\"0bca48e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Elige c\u00f3mo jugar<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a66e4b7 elementor-widget elementor-widget-heading\" data-id=\"a66e4b7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aventura virtual<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5da6d99 elementor-widget elementor-widget-image\" data-id=\"5da6d99\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.12.1 - 02-04-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bentonco.spectrespast.com\/es\/week-one-bridging-the-divide\/week-1-web\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"450\" height=\"167\" src=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresVirtualE1C1.png\" class=\"attachment-large size-large wp-image-2435\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresVirtualE1C1.png 450w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresVirtualE1C1-300x111.png 300w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresVirtualE1C1-16x6.png 16w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77db0d7 elementor-widget elementor-widget-image\" data-id=\"77db0d7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bentonco.spectrespast.com\/es\/week-one-bridging-the-divide\/courthouse-crackers\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"450\" height=\"167\" src=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresVirtualE1C2.png\" class=\"attachment-large size-large wp-image-2436\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresVirtualE1C2.png 450w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresVirtualE1C2-300x111.png 300w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresVirtualE1C2-16x6.png 16w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6797470 elementor-widget elementor-widget-spacer\" data-id=\"6797470\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.12.1 - 02-04-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d064df5 elementor-widget elementor-widget-heading\" data-id=\"d064df5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">En el piso<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2ae88c elementor-widget elementor-widget-text-editor\" data-id=\"e2ae88c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Piezas de juego en PDF<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba150cc elementor-invisible elementor-widget elementor-widget-image\" data-id=\"ba150cc\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/Week-One-Challenge-1.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"360\" height=\"108\" src=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresPDFdownloadE1C1-1.png\" class=\"attachment-large size-large wp-image-2308\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresPDFdownloadE1C1-1.png 360w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresPDFdownloadE1C1-1-300x90.png 300w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresPDFdownloadE1C1-1-16x5.png 16w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77f3fd2 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"77f3fd2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/Week-One-Challenge-2.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"360\" height=\"108\" src=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresPDFdownloadE1C2-1.png\" class=\"attachment-large size-large wp-image-2309\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresPDFdownloadE1C2-1.png 360w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresPDFdownloadE1C2-1-300x90.png 300w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresPDFdownloadE1C2-1-16x5.png 16w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e39f49 elementor-widget elementor-widget-text-editor\" data-id=\"5e39f49\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Aplicaci\u00f3n Actionbound<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ece2a2 elementor-widget elementor-widget-image\" data-id=\"4ece2a2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"111\" src=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresActionboundE1C1-300x111.png\" class=\"attachment-medium size-medium wp-image-2320\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresActionboundE1C1-300x111.png 300w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresActionboundE1C1-16x6.png 16w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresActionboundE1C1.png 450w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea579d9 elementor-widget elementor-widget-image\" data-id=\"ea579d9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"108\" height=\"175\" src=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/ghost-between-bounds.png\" class=\"attachment-large size-large wp-image-2355\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/ghost-between-bounds.png 108w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/ghost-between-bounds-7x12.png 7w\" sizes=\"(max-width: 108px) 100vw, 108px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2083e7e elementor-widget elementor-widget-image\" data-id=\"2083e7e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"111\" src=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresActionboundE1C2-300x111.png\" class=\"attachment-medium size-medium wp-image-2321\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresActionboundE1C2-300x111.png 300w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresActionboundE1C2-16x6.png 16w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresActionboundE1C2.png 450w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d54f6d0 elementor-widget elementor-widget-text-editor\" data-id=\"d54f6d0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00bfNo tiene Actionbound instalado en su tel\u00e9fono inteligente? \u00a1Haga click abajo!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9264f2 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d9264f2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"\/es\/actionbound\/\" class=\"elementor-button-link elementor-button elementor-size-lg\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Presione para obtener instrucciones para instalar Actionbound<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3af74ab elementor-widget elementor-widget-spacer\" data-id=\"3af74ab\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d50437 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d50437\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b5cbdf\" data-id=\"7b5cbdf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62c4dff elementor-widget elementor-widget-heading\" data-id=\"62c4dff\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Los recursos hist\u00f3ricos que inspiraron los desaf\u00edos del episodio uno<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-83919de elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"83919de\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fe4bcb4\" data-id=\"fe4bcb4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-502f1ce elementor-widget elementor-widget-image\" data-id=\"502f1ce\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"432\" src=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/Circa1890.jpeg\" class=\"attachment-full size-full wp-image-2252\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/Circa1890.jpeg 640w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/Circa1890-300x203.jpeg 300w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/Circa1890-16x12.jpeg 16w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea5bf6c elementor-widget elementor-widget-text-editor\" data-id=\"ea5bf6c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Construido en 1888, el Palacio de Justicia del Condado de Benton es el palacio de justicia m\u00e1s antiguo de Oregon que todav\u00eda se utiliza como palacio de justicia. A trav\u00e9s de los a\u00f1os, el Palacio de Justicia del Condado de Benton ha recolectado varios fantasmas, tuvo un momento de dinamita en 1909 y contin\u00faa brillando como la joya de la corona del Condado de Benton. Uno de los fantasmas reportados aparece como un caballero con sombrero hongo y uniforme de la Guerra Civil de la Uni\u00f3n y se cree que es Martin T. Lindsey, fue capturado llevando un mensaje a trav\u00e9s de las l\u00edneas enemigas y fue encarcelado en la prisi\u00f3n de Andersonville en Georgia. El Sr. Lindsey est\u00e1 enterrado en el cementerio de Crystal Lake bajo una estrella del Gran Ej\u00e9rcito de la Rep\u00fablica.<\/span><\/p><p><span style=\"font-weight: 400;\">Informaci\u00f3n adicional sobre el <\/span><a href=\"https:\/\/www.co.benton.or.us\/sites\/default\/files\/fileattachments\/courthouse_preservation_committee\/page\/5830\/flight_of_time_optimized.pdf\"><span style=\"font-weight: 400;\">Palacio de justicia del condado de Benton<\/span><\/a><span style=\"font-weight: 400;\"> o las inquietantes condiciones en <\/span><a href=\"https:\/\/www.nps.gov\/ande\/learn\/historyculture\/camp_sumter_history.htm\"><span style=\"font-weight: 400;\">Prisi\u00f3n de Andersonville<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d978674\" data-id=\"d978674\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17d0295 elementor-widget elementor-widget-image\" data-id=\"17d0295\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"432\" src=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresVanBurenOpening.png\" class=\"attachment-full size-full wp-image-2261\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresVanBurenOpening.png 640w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresVanBurenOpening-300x203.png 300w, https:\/\/bentonco.spectrespast.com\/wp-content\/uploads\/2021\/05\/SpectresVanBurenOpening-16x12.png 16w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-beae648 elementor-widget elementor-widget-text-editor\" data-id=\"beae648\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">El puente Van Buren es el primero en varios frentes: fue la primera oportunidad para que las mujeres de Corvallis emitieran su voto * y fue el primer puente de Corvallis en cruzar el Willamette, reemplazando m\u00e1s de 50 a\u00f1os de traves\u00edas en ferry. El Puente Van Buren es el \u00fanico puente m\u00f3vil al oeste del Mississippi construido con una tecnolog\u00eda de conexi\u00f3n de pines poco com\u00fan. George Way, un lavaplatos asi\u00e1tico-estadounidense en el Hotel Julian de Corvallis, se qued\u00f3 atascado en el puente en 1914 cuando una fuerte tormenta de viento lo abri\u00f3.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Para obtener m\u00e1s informaci\u00f3n sobre <\/span><a href=\"https:\/\/www.presworks.org\/van-buren-bridge\"><span style=\"font-weight: 400;\">Puente Van Buren<\/span><\/a><span style=\"font-weight: 400;\"> o ser\u00a0 <\/span><a href=\"https:\/\/www.oregonencyclopedia.org\/articles\/chinese_americans_in_oregon\/#.YIhrF-hKg2w\"><span style=\"font-weight: 400;\">Chino americano en Oregon<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Su aventura comienza en una estructura que fue innovadora en su \u00e9poca: 1913: el puente van Buren; y en su prop\u00f3sito: conectar personas y medios de transporte hacia el condado de Benton y Corvallis sobre el caudaloso r\u00edo Willamette. \u00a1Imag\u00ednese atravesar un fino velo en el tiempo y el espacio que lo llevar\u00e1 a una misi\u00f3n de rescate! Aunque rescatar a un\u2026 <a title=\"Episodio uno - Uniendo la brecha\" class=\"read-more\" href=\"https:\/\/bentonco.spectrespast.com\/es\/game-landing-page\/week-one-bridging-the-divide\/\" aria-label=\"M\u00e1s en Episodio uno \u2013 Uniendo la brecha\">Leer m\u00e1s<\/a><\/p>","protected":false},"author":2,"featured_media":0,"parent":957,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"folder":[59],"acf":[],"_links":{"self":[{"href":"https:\/\/bentonco.spectrespast.com\/es\/wp-json\/wp\/v2\/pages\/1016"}],"collection":[{"href":"https:\/\/bentonco.spectrespast.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bentonco.spectrespast.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bentonco.spectrespast.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bentonco.spectrespast.com\/es\/wp-json\/wp\/v2\/comments?post=1016"}],"version-history":[{"count":249,"href":"https:\/\/bentonco.spectrespast.com\/es\/wp-json\/wp\/v2\/pages\/1016\/revisions"}],"predecessor-version":[{"id":3523,"href":"https:\/\/bentonco.spectrespast.com\/es\/wp-json\/wp\/v2\/pages\/1016\/revisions\/3523"}],"up":[{"embeddable":true,"href":"https:\/\/bentonco.spectrespast.com\/es\/wp-json\/wp\/v2\/pages\/957"}],"wp:attachment":[{"href":"https:\/\/bentonco.spectrespast.com\/es\/wp-json\/wp\/v2\/media?parent=1016"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/bentonco.spectrespast.com\/es\/wp-json\/wp\/v2\/folder?post=1016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}